{"id":670,"date":"2021-04-28T11:34:17","date_gmt":"2021-04-28T09:34:17","guid":{"rendered":"http:\/\/www.coprogetti.it\/progetti\/prrenjas-general-local-plan\/"},"modified":"2021-10-12T15:24:31","modified_gmt":"2021-10-12T13:24:31","slug":"prrenjas-general-local-plan","status":"publish","type":"progetto","link":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/","title":{"rendered":"Prrenjas General Local Plan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Prrenjas General Local Plan.<\/p>\n","protected":false},"featured_media":665,"template":"","categories":[23],"class_list":["post-670","progetto","type-progetto","status-publish","has-post-thumbnail","hentry","category-urban-planning"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prrenjas General Local Plan - Cooprogetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prrenjas General Local Plan - Cooprogetti\" \/>\n<meta property=\"og:description\" content=\"Prrenjas General Local Plan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooprogetti\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-12T13:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/\",\"url\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/\",\"name\":\"Prrenjas General Local Plan - Cooprogetti\",\"isPartOf\":{\"@id\":\"http:\/\/www.coprogetti.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg\",\"datePublished\":\"2021-04-28T09:34:17+00:00\",\"dateModified\":\"2021-10-12T13:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage\",\"url\":\"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg\",\"contentUrl\":\"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.coprogetti.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\/\/www.coprogetti.it\/en\/archivio-progetti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prrenjas General Local Plan\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.coprogetti.it\/#website\",\"url\":\"http:\/\/www.coprogetti.it\/\",\"name\":\"Cooprogetti\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.coprogetti.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prrenjas General Local Plan - Cooprogetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/","og_locale":"en_US","og_type":"article","og_title":"Prrenjas General Local Plan - Cooprogetti","og_description":"Prrenjas General Local Plan.","og_url":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/","og_site_name":"Cooprogetti","article_modified_time":"2021-10-12T13:24:31+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/","url":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/","name":"Prrenjas General Local Plan - Cooprogetti","isPartOf":{"@id":"http:\/\/www.coprogetti.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage"},"image":{"@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg","datePublished":"2021-04-28T09:34:17+00:00","dateModified":"2021-10-12T13:24:31+00:00","breadcrumb":{"@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#primaryimage","url":"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg","contentUrl":"https:\/\/www.coprogetti.it\/wp-content\/uploads\/2021\/04\/prrenjas-main.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.coprogetti.it\/en\/progetti\/prrenjas-general-local-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.coprogetti.it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/www.coprogetti.it\/en\/archivio-progetti\/"},{"@type":"ListItem","position":3,"name":"Prrenjas General Local Plan"}]},{"@type":"WebSite","@id":"http:\/\/www.coprogetti.it\/#website","url":"http:\/\/www.coprogetti.it\/","name":"Cooprogetti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.coprogetti.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/progetto\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/progetto"}],"about":[{"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/types\/progetto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/media\/665"}],"wp:attachment":[{"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/media?parent=670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coprogetti.it\/en\/wp-json\/wp\/v2\/categories?post=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}